{"id":41,"count":1,"description":"","link":"https:\/\/skillire.com\/index.php\/candidate-category\/application\/","name":"Application","slug":"application","taxonomy":"candidate_category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/candidate_category\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/candidate_category"}],"about":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/candidate_category"}],"wp:post_type":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/candidate?candidate_category=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}