{"id":38,"count":5,"description":"","link":"https:\/\/skillire.com\/index.php\/candidate-tag\/app\/","name":"app","slug":"app","taxonomy":"candidate_tag","meta":[],"_links":{"self":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/candidate_tag\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/candidate_tag"}],"about":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/candidate_tag"}],"wp:post_type":[{"href":"https:\/\/skillire.com\/index.php\/wp-json\/wp\/v2\/candidate?candidate_tag=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}